{"id":1839,"date":"2020-01-21T10:06:37","date_gmt":"2020-01-21T09:06:37","guid":{"rendered":"https:\/\/www.climsom.com\/blog\/?p=1839"},"modified":"2024-07-30T11:01:28","modified_gmt":"2024-07-30T10:01:28","slug":"jambes-sans-repos-que-faire-pour-retrouver-le-sommeil","status":"publish","type":"post","link":"https:\/\/www.climsom.com\/blog\/jambes-sans-repos-que-faire-pour-retrouver-le-sommeil\/","title":{"rendered":"Jambes sans repos : que faire pour retrouver le sommeil ?"},"content":{"rendered":"\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous souffrez du <strong>syndrome des jambes sans repos<\/strong> <strong>(SJSR<\/strong>), aussi appel\u00e9 <strong>maladie de Willis Ekbom<\/strong>, vous savez que le mouvement soulage les douleurs des impatiences de m\u00eame que l\u2019application de froid. Alors vous sortez de votre lit et appliquez des compresses froides tout en faisant les cent pas dans la maison. Mais sit\u00f4t de retour dans votre lit, les douleurs reprennent de plus belle&nbsp;! Comment r\u00e9duire ces sensations d\u00e9sagr\u00e9ables et douloureuses qui retardent votre endormissement&nbsp;? <\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Les bienfaits du froid pour soulager les impatiences<\/strong><\/h2>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Sa propri\u00e9t\u00e9 <strong>antalgique<\/strong> fait du froid un alli\u00e9 pr\u00e9cieux pour lutter contre les douleurs du syndrome des jambes sans repos. C&rsquo;est \u00e0 partir de ce constat que nous avons eu l&rsquo;id\u00e9e de cr\u00e9er un <strong>sur-matelas climatis\u00e9<\/strong> pour soulager les impatiences.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><a href=\"https:\/\/www.climsom.com\/fra\/sur-matelas-rafraichissant-chauffant-jambes-lourdes.php?codeoffer=CS&amp;SCT=CLI&amp;UNV=ESS&amp;PNS=\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"375\" height=\"300\" src=\"https:\/\/www.climsom.com\/blog\/wp-content\/uploads\/2015\/07\/surmatelas-jambes-lourdes-1-375x300.jpg\" alt=\"surmatelas climatis\u00e9\" class=\"wp-image-125\" srcset=\"https:\/\/www.climsom.com\/blog\/wp-content\/uploads\/2015\/07\/surmatelas-jambes-lourdes-1-375x300.jpg 375w, https:\/\/www.climsom.com\/blog\/wp-content\/uploads\/2015\/07\/surmatelas-jambes-lourdes-1-300x240.jpg 300w, https:\/\/www.climsom.com\/blog\/wp-content\/uploads\/2015\/07\/surmatelas-jambes-lourdes-1.jpg 500w\" sizes=\"auto, (max-width: 375px) 100vw, 375px\" \/><\/a><figcaption class=\"wp-element-caption\"><em>Le <strong><a href=\"https:\/\/www.climsom.com\/fra\/sur-matelas-rafraichissant-chauffant-jambes-lourdes.php?codeoffer=CS&amp;SCT=CLI&amp;UNV=ESS&amp;PNS=\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"sur-matelas Climsom (s\u2019ouvre dans un nouvel onglet)\">sur-matelas Climsom<\/a><\/strong> : un alli\u00e9 contre le SJSR !<\/em><\/figcaption><\/figure>\n<\/div>\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">C&rsquo;\u00e9tait il y a 10 ans. Nous avions rencontr\u00e9 le Dr Tamburini, phl\u00e9bologue, et ensemble nous cherchions une <strong>solution durable<\/strong> pour ses patients souffrant de <strong>troubles du sommeil<\/strong> li\u00e9s \u00e0 l\u2019insuffisance veineuse et aux impatiences. C&rsquo;est ainsi qu&rsquo;est n\u00e9 le sur-matelas Climsom qui a depuis trouv\u00e9 un large public tout en r\u00e9pondant aux attentes des personnes souffrant de la maladie des jambes sans repos.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-very-dark-gray-color has-very-light-gray-background-color has-text-color has-background wp-block-paragraph\"><strong>Avis de Daniel L. sur le sur-matelas Climsom :<\/strong><br>\u00ab\u00a0<em>J&rsquo;ai 61 ans. Je pratique le v\u00e9lo (3 500 \u00e0 4 000 kms\/an) mais cela ne m&#8217;emp\u00eache pas de souffrir du syndrome des jambes sans repos, au point que j&rsquo;appr\u00e9hendais le moment de me mettre au lit. R\u00e9veill\u00e9 plusieurs fois par nuit, et \u00e0 la recherche perp\u00e9tuelle de zones fraiches, mon sommeil n&rsquo;\u00e9tait pas r\u00e9cup\u00e9rateur. Mon chirurgien ne voyant pas la n\u00e9cessit\u00e9 d&rsquo;une op\u00e9ration, je me suis d\u00e9cid\u00e9, sur conseil de mon ang\u00e9iologue, \u00e0 acheter un sur-matelas Climsom. D\u00e8s la premi\u00e8re nuit, <strong>j&rsquo;ai trouv\u00e9 un r\u00e9el confort<\/strong>. Je r\u00e8gle la temp\u00e9rature entre 24 et 26 degr\u00e9s et enfin <strong>mes nuits sont reposantes<\/strong>.<\/em>\u00ab\u00a0<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Pourquoi le sur-matelas Climsom est-il une solution adapt\u00e9e au SJSR&nbsp;?<\/strong><\/h2>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Fra\u00eecheur durable toute la nuit<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Avec le sur-matelas Climsom, <strong>vous contr\u00f4lez vous-m\u00eame la temp\u00e9rature de votre lit<\/strong>. Allongez-vous sur le sur-matelas et, depuis votre lit, gr\u00e2ce \u00e0 la t\u00e9l\u00e9commande, choisissez la temp\u00e9rature souhait\u00e9e. Le sur-matelas Climsom peut descendre jusqu\u2019\u00e0 18\u00b0C&nbsp;! L\u2019eau refroidie dans le thermo-contr\u00f4leur va alors \u00eatre achemin\u00e9e dans le sur-matelas gr\u00e2ce \u00e0 un r\u00e9seau de fines tubulures, vous procurant une <strong>fra\u00eecheur durable et apaisante<\/strong>. <\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><a href=\"https:\/\/www.climsom.com\/fra\/sur-matelas-rafraichissant-chauffant-jambes-lourdes.php?codeoffer=CS&amp;SCT=CLI&amp;UNV=&amp;PNS=\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"454\" height=\"300\" src=\"https:\/\/www.climsom.com\/blog\/wp-content\/uploads\/2020\/01\/Climsom_Surmatelas_Personal_fonctionnement_froid_dessin_web-454x300.jpg\" alt=\"\" class=\"wp-image-1845\" srcset=\"https:\/\/www.climsom.com\/blog\/wp-content\/uploads\/2020\/01\/Climsom_Surmatelas_Personal_fonctionnement_froid_dessin_web-454x300.jpg 454w, https:\/\/www.climsom.com\/blog\/wp-content\/uploads\/2020\/01\/Climsom_Surmatelas_Personal_fonctionnement_froid_dessin_web-300x198.jpg 300w, https:\/\/www.climsom.com\/blog\/wp-content\/uploads\/2020\/01\/Climsom_Surmatelas_Personal_fonctionnement_froid_dessin_web-768x507.jpg 768w, https:\/\/www.climsom.com\/blog\/wp-content\/uploads\/2020\/01\/Climsom_Surmatelas_Personal_fonctionnement_froid_dessin_web-1536x1015.jpg 1536w, https:\/\/www.climsom.com\/blog\/wp-content\/uploads\/2020\/01\/Climsom_Surmatelas_Personal_fonctionnement_froid_dessin_web-370x244.jpg 370w, https:\/\/www.climsom.com\/blog\/wp-content\/uploads\/2020\/01\/Climsom_Surmatelas_Personal_fonctionnement_froid_dessin_web-1040x687.jpg 1040w, https:\/\/www.climsom.com\/blog\/wp-content\/uploads\/2020\/01\/Climsom_Surmatelas_Personal_fonctionnement_froid_dessin_web.jpg 2000w\" sizes=\"auto, (max-width: 454px) 100vw, 454px\" \/><\/a><\/figure>\n<\/div>\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Temp\u00e9rature r\u00e9glable au degr\u00e9 pr\u00e8s et programmable<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Certaines personnes souffrant du syndrome des jambes sans repos notent une aggravation des sympt\u00f4mes par la chaleur. Le sur-matelas Climsom permet de r\u00e9gler la temp\u00e9rature du lit <strong>au degr\u00e9 pr\u00e8s<\/strong> afin de r\u00e9duire ce risque et il peut m\u00eame \u00eatre programm\u00e9.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-very-light-gray-background-color has-background wp-block-paragraph\"><strong>Avis de Anne R. sur le sur-matelas Climsom :<\/strong><br>\u00ab\u00a0<em>Je souffre d&rsquo;impatiences nocturnes au niveau des jambes. Je r\u00e8gle l&rsquo;appareil en fonction diff\u00e9r\u00e9e, afin qu&rsquo;il d\u00e9marre deux heures apr\u00e8s m&rsquo;\u00eatre couch\u00e9e, ceci sur 25\u00b0. J&rsquo;ai, par ailleurs pris soin d&rsquo;isoler la hauteur du dos de la fra\u00eecheur. <strong>L&rsquo;utilisation du surmatelas me fait passer de meilleures nuits.<\/strong>\u00ab\u00a0<\/em><\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Comme le recommande Anne, vous pouvez  placer votre sur-matelas de mani\u00e8re \u00e0 ce qu&rsquo;il n&rsquo;agisse que sur les jambes. Sachez aussi que le Climsom se d\u00e9cline en diff\u00e9rents mod\u00e8les dont le <strong><a rel=\"noreferrer noopener\" aria-label=\"Climsom Intense (s\u2019ouvre dans un nouvel onglet)\" href=\"https:\/\/www.climsom.com\/fra\/pack-intense.php?codeoffer=CPackIntense&amp;SCT=CLI&amp;UNV=ESS&amp;PNS=\" target=\"_blank\">Climsom Intense<\/a><\/strong>. Avec sa taille limit\u00e9e (70&#215;100), vous pouvez concentrer toute la fra\u00eecheur sur une zone pr\u00e9cise de votre corps. Le Climsom Intense peut descendre jusqu&rsquo;\u00e0 15\u00b0C ! Une fra\u00eecheur saisissante particuli\u00e8rement appr\u00e9ci\u00e9e par les personnes souffrant d&rsquo;impatiences.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><a href=\"https:\/\/www.climsom.com\/fra\/pack-intense.php?codeoffer=CPackIntense&amp;SCT=CLI&amp;UNV=ESS&amp;PNS=\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/www.climsom.com\/blog\/wp-content\/uploads\/2016\/07\/surmatelas-rafraichissant-intense-climsom-450x300.jpg\" alt=\"soulager jambes lourdes\" class=\"wp-image-422\"\/><\/a><figcaption class=\"wp-element-caption\"><em>Profitez de la fra\u00eecheur localis\u00e9e du <strong><a href=\"https:\/\/www.climsom.com\/fra\/pack-intense.php?codeoffer=CPackIntense&amp;SCT=CLI&amp;UNV=ESS&amp;PNS=\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"Climsom Intense (s\u2019ouvre dans un nouvel onglet)\">Climsom Intense<\/a><\/strong> <\/em>!<\/figcaption><\/figure>\n<\/div>\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong>Le saviez-vous ?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La temp\u00e9rature agit sur la cr\u00e9ation de la m\u00e9latonine, une hormone cl\u00e9 dans la r\u00e9gulation du sommeil.<\/p>\n<\/blockquote>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>R\u00e9duction des mouvements nocturnes<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Le sur-matelas Climsom facilite l\u2019endormissement en vous faisant profiter des bienfaits du froid aussi longtemps que vous le souhaitez. Le Professeur Damien L\u00e9ger du Centre du Sommeil et de la Vigilance de l\u2019H\u00f4tel Dieu a r\u00e9alis\u00e9 une <a rel=\"noreferrer noopener\" aria-label=\"\u00e9tude \u00e0 propos du sur-matelas Climsom (s\u2019ouvre dans un nouvel onglet)\" href=\"https:\/\/www.climsom.com\/fra\/etude-centre-sommeil-leger-2011.php\" target=\"_blank\">\u00e9tude \u00e0 propos du sur-matelas Climsom<\/a> dont voici les principaux r\u00e9sultats&nbsp;:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Am\u00e9lioration de la qualit\u00e9 de la nuit : + 58%<\/li>\n\n\n\n<li>Des nuits plus calmes : -24,5% de mouvements nocturnes<\/li>\n\n\n\n<li>Augmentation du temps de sommeil : +23 minutes<\/li>\n\n\n\n<li>Am\u00e9lioration du dynamisme au r\u00e9veil de +48%<\/li>\n\n\n\n<li>Diminution de la somnolence en journ\u00e9e de +33%<\/li>\n\n\n\n<li>Am\u00e9lioration de la qualit\u00e9 de la journ\u00e9e : + 19%   <\/li>\n<\/ul>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Le Climsom est ainsi pr\u00e9sent\u00e9 comme une \u00ab\u00a0<strong>alternative int\u00e9ressante (et totalement inoffensive) aux traitements m\u00e9dicamenteux<\/strong>\u00a0\u00bb par le <a href=\"http:\/\/www.sommeil-mg.net\/spip\/Sommeil-degrade-Impatience-et\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"Docteur Guilhem P\u00e9r\u00e9marty, (s\u2019ouvre dans un nouvel onglet)\">Docteur Guilhem P\u00e9r\u00e9marty,<\/a> sp\u00e9cialis\u00e9 en m\u00e9decine du sommeil, dipl\u00f4m\u00e9 et membre de la SFRMS, Soci\u00e9t\u00e9 Fran\u00e7aise de Recherche et M\u00e9decine du Sommeil.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.climsom.com\/blog\/wp-content\/uploads\/2020\/01\/Image_thematique_fraicheur_pieds_dans_mer-300x300.jpg\" alt=\"fraicheur_pieds_dans_mer\" class=\"wp-image-1844\"\/><figcaption class=\"wp-element-caption\"><em>Avec le <strong><a rel=\"noreferrer noopener\" aria-label=\"Climsom (s\u2019ouvre dans un nouvel onglet)\" href=\"https:\/\/www.climsom.com\/fra\/sur-matelas-rafraichissant-chauffant-jambes-lourdes.php?codeoffer=CS&amp;SCT=CLI&amp;UNV=&amp;PNS=\" target=\"_blank\">Climsom<\/a><\/strong>, vous revivez !<\/em><\/figcaption><\/figure>\n<\/div>\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Ces r\u00e9sultats confirment le ressenti des utilisateurs et ce, quelle que soit l\u2019intensit\u00e9 de leur SJSR&nbsp;:<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-very-light-gray-background-color has-background wp-block-paragraph\"><strong>Avis de Jeanne L. sur le<\/strong> <strong>sur-matelas Climsom :<\/strong><br>\u00ab\u00a0<em>Personnellement, je pr\u00e9sente un syndrome des jambes sans repos mineur se traduisant par des impatiences nocturnes des jambes et des bras. Gr\u00e2ce au frais apport\u00e9 par le Climsom r\u00e9gl\u00e9 \u00e0 22 degr\u00e9s <strong>je m&rsquo;endors facilement<\/strong>, le froid ayant un effet calmant et apaisant. <strong>Je parviens donc \u00e0 faire des nuits compl\u00e8tes m\u00eame lorsqu&rsquo;une crise survient<\/strong>. J&rsquo;ai d&rsquo;ailleurs pris l&rsquo;habitude de dormir toutes les nuits \u00e0 cette temp\u00e9rature&#8230;\u00a0\u00bb<\/em><\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-very-light-gray-background-color has-background wp-block-paragraph\"><strong>Avis de Nathalie sur le sur-matelas Climsom :<\/strong><br>\u00ab\u00a0<em>J&rsquo;ai 37 ans et depuis une dizaine d&rsquo;ann\u00e9es, je souffre d&rsquo;un syndrome des jambes sans repos s\u00e9v\u00e8re. Aucun m\u00e9dicament sur le march\u00e9 ne me soulage vraiment longtemps. Un jour de d\u00e9sespoir, apr\u00e8s une s\u00e9rie de tr\u00e8s mauvaises nuits et de fatigue accumul\u00e9e, j&rsquo;ai surf\u00e9 sur le net et suis tomb\u00e9e sur le concept CLIMSON ! <strong>Une r\u00e9volution dans ma vie ! <\/strong>Ca fait environ 1 an que je l&rsquo;ai. J&rsquo;utilise le matelas \u00e0 sa temp\u00e9rature la plus froide (18\u00b0C) et ce 365 jours\/365. Par contre pour \u00e9viter de congeler, je n&rsquo;utilise que la moiti\u00e9 du matelas afin qu&rsquo;il rafraichisse mes jambes uniquement. L&rsquo;autre moiti\u00e9 est soigneusement repli\u00e9e sous le matelas. Mon syndrome n&rsquo;a \u00e9videmment pas disparu mais je peux dire que <strong>la qualit\u00e9 de mes nuits s&rsquo;en est trouv\u00e9e nettement am\u00e9lior\u00e9e<\/strong>. Le traitement que je prends actuellement (Rivotril) me soulage d&rsquo;environ 40%, <strong>Climson a am\u00e9lior\u00e9 mon sommeil d&rsquo;environ 30%<\/strong>&#8230; R\u00e9sultat: mes nuits sont \u00e0 70% parfaites !<\/em><strong><em>\u00ab\u00a0<\/em><\/strong><\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Il arrive aussi que les mouvements involontaires de la personne souffrant des jambes sans repos perturbent aussi le sommeil du conjoint. Dans certains cas, le conjoint finit par dormir dans un lit s\u00e9par\u00e9 ou peut m\u00eame d\u00e9cider de faire chambre \u00e0 part afin de pr\u00e9server la qualit\u00e9 de son sommeil. Avec le sur-matelas Climsom Personal, am\u00e9liorez la qualit\u00e9 de vos nuits et celle de votre conjoint !<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/www.climsom.com\/blog\/wp-content\/uploads\/2020\/01\/Image_thematique_Amour_couple_vieux.jpg\" alt=\"amour-couple-vieux-heureux\" class=\"wp-image-1847\" srcset=\"https:\/\/www.climsom.com\/blog\/wp-content\/uploads\/2020\/01\/Image_thematique_Amour_couple_vieux.jpg 400w, https:\/\/www.climsom.com\/blog\/wp-content\/uploads\/2020\/01\/Image_thematique_Amour_couple_vieux-300x225.jpg 300w, https:\/\/www.climsom.com\/blog\/wp-content\/uploads\/2020\/01\/Image_thematique_Amour_couple_vieux-370x278.jpg 370w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/figure>\n<\/div>\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Un sur-matelas rafraichissant aux nombreux bienfaits<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Le sur-matelas Climsom poss\u00e8de bien d\u2019autres atouts parmi lesquels&nbsp;: <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Am\u00e9lioration de l\u2019hygi\u00e8ne du lit<\/strong>\u00a0: la r\u00e9duction de la chaleur va diminuer la transpiration nocturne r\u00e9duisant ainsi le nombre d\u2019acariens<\/li>\n\n\n\n<li>Utilisation possible du chaud pour <strong>se d\u00e9tendre\u00a0et se relaxer<\/strong>\u00a0: un bon moyen de r\u00e9duire le stress<\/li>\n\n\n\n<li><strong>Dispositif s\u00e9curis\u00e9<\/strong>\u00a0: votre corps n\u2019est pas en contact avec un r\u00e9seau \u00e9lectrique<\/li>\n\n\n\n<li>Vous souffrez de <strong>bouff\u00e9es de chaleur<\/strong>\u00a0? Le Climsom a prouv\u00e9 ses bienfaits pour retrouver des nuits paisibles.  <\/li>\n<\/ul>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Les retours des utilisateurs nous confirment que le Climsom r\u00e9pond \u00e0 leurs attentes et les aide \u00e0 soulager leurs douleurs dans la plupart des cas. Si jamais \u00e7a n&rsquo;\u00e9tait pas le v\u00f4tre, sachez que le Climsom b\u00e9n\u00e9ficie de la garantie \u00ab&nbsp;<strong>30 jours<\/strong> <strong>\u00ab\u00a0Satisfait ou Rembours\u00e9\u00a0\u00bb<\/strong> \u00bb. Vous pouvez donc prendre le temps de le tester et voir s\u2019il vous convient. Et, comme Francine, vous ne pourrez bient\u00f4t plus vous en passer&nbsp;:<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-very-light-gray-background-color has-background wp-block-paragraph\"><strong>Avis de Francine sur le sur-matelas Climsom :<\/strong><br>\u00ab\u00a0<em>J&rsquo;ai la maladie des \u00ab\u00a0jambes sans repos\u00a0\u00bb ou impatiences dans les jambes tout particuli\u00e8rement en \u00e9tant allong\u00e9e. Je l&rsquo;utilise donc pour les jambes en mettant une temp\u00e9rature tr\u00e8s froide et <strong>\u00e7a me permet de dormir correctement sans tous les d\u00e9sagr\u00e9ments, \u00e7a change tout simplement ma vie<\/strong> <strong>!!!<\/strong>\u00ab\u00a0<\/em><\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-button aligncenter\"><a class=\"wp-block-button__link has-background wp-element-button\" href=\"https:\/\/www.climsom.com\/eur\/ClimsomShopHP.php?SCT=CLI&amp;UNV=ESS\" style=\"background-color:#209bbc\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Soulagez vos impatiences avec le sur-matelas Climsom !<\/strong><\/a><\/div>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Il existe d\u2019autres solutions compl\u00e9mentaires pour soulager les impatiences. Si le sur-matelas climatis\u00e9 Climsom peut vous aider \u00e0 passer de meilleures nuits, l&rsquo;acupression peut vous aider \u00e0 passer de meilleures journ\u00e9es.<\/em><\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-button aligncenter\"><a class=\"wp-block-button__link has-background wp-element-button\" href=\"https:\/\/www.climsom.com\/blog\/sjsr-comment-l-acupression-peut-soulager-les-impatiences\/\" style=\"background-color:#209bbc\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Comment l&rsquo;acupression peut aider \u00e0 soulager le SJSR ?<\/strong><\/a><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Comment soulager les impatiences durablement pour r\u00e9ussir \u00e0 dormir ? D\u00e9couvrez une solution pour retrouver un sommeil de qualit\u00e9 !<\/p>\n","protected":false},"author":1,"featured_media":1841,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,8],"tags":[62,61,60],"class_list":["post-1839","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sante","category-sommeil","tag-impatiences","tag-sjsr","tag-trouble-du-sommeil"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jambes sans repos : que faire pour retrouver le sommeil ? - Climsom \u2013 L\u2019innovation bien-\u00eatre<\/title>\n<meta name=\"description\" content=\"Avec le sur-matelas climatis\u00e9 Climsom, r\u00e9duisez les impatiences du syndrome des jambes sans repos pour retrouver un sommeil de qualit\u00e9 !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.climsom.com\/blog\/jambes-sans-repos-que-faire-pour-retrouver-le-sommeil\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jambes sans repos : que faire pour retrouver le sommeil ? - Climsom \u2013 L\u2019innovation bien-\u00eatre\" \/>\n<meta property=\"og:description\" content=\"Avec le sur-matelas climatis\u00e9 Climsom, r\u00e9duisez les impatiences du syndrome des jambes sans repos pour retrouver un sommeil de qualit\u00e9 !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.climsom.com\/blog\/jambes-sans-repos-que-faire-pour-retrouver-le-sommeil\/\" \/>\n<meta property=\"og:site_name\" content=\"Climsom \u2013 L\u2019innovation bien-\u00eatre\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-21T09:06:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-30T10:01:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.climsom.com\/blog\/wp-content\/uploads\/2020\/01\/sommeil_femme_lit.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"272\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"climsom\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"climsom\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.climsom.com\\\/blog\\\/jambes-sans-repos-que-faire-pour-retrouver-le-sommeil\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.climsom.com\\\/blog\\\/jambes-sans-repos-que-faire-pour-retrouver-le-sommeil\\\/\"},\"author\":{\"name\":\"climsom\",\"@id\":\"https:\\\/\\\/www.climsom.com\\\/blog\\\/#\\\/schema\\\/person\\\/ad3a50ac6861affad1c0acafec04bb15\"},\"headline\":\"Jambes sans repos : que faire pour retrouver le sommeil ?\",\"datePublished\":\"2020-01-21T09:06:37+00:00\",\"dateModified\":\"2024-07-30T10:01:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.climsom.com\\\/blog\\\/jambes-sans-repos-que-faire-pour-retrouver-le-sommeil\\\/\"},\"wordCount\":1476,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.climsom.com\\\/blog\\\/jambes-sans-repos-que-faire-pour-retrouver-le-sommeil\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.climsom.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/sommeil_femme_lit.jpg\",\"keywords\":[\"impatiences\",\"SJSR\",\"trouble du sommeil\"],\"articleSection\":[\"Sant\u00e9\",\"Sommeil\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.climsom.com\\\/blog\\\/jambes-sans-repos-que-faire-pour-retrouver-le-sommeil\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.climsom.com\\\/blog\\\/jambes-sans-repos-que-faire-pour-retrouver-le-sommeil\\\/\",\"url\":\"https:\\\/\\\/www.climsom.com\\\/blog\\\/jambes-sans-repos-que-faire-pour-retrouver-le-sommeil\\\/\",\"name\":\"Jambes sans repos : que faire pour retrouver le sommeil ? - Climsom \u2013 L\u2019innovation bien-\u00eatre\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.climsom.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.climsom.com\\\/blog\\\/jambes-sans-repos-que-faire-pour-retrouver-le-sommeil\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.climsom.com\\\/blog\\\/jambes-sans-repos-que-faire-pour-retrouver-le-sommeil\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.climsom.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/sommeil_femme_lit.jpg\",\"datePublished\":\"2020-01-21T09:06:37+00:00\",\"dateModified\":\"2024-07-30T10:01:28+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.climsom.com\\\/blog\\\/#\\\/schema\\\/person\\\/ad3a50ac6861affad1c0acafec04bb15\"},\"description\":\"Avec le sur-matelas climatis\u00e9 Climsom, r\u00e9duisez les impatiences du syndrome des jambes sans repos pour retrouver un sommeil de qualit\u00e9 !\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.climsom.com\\\/blog\\\/jambes-sans-repos-que-faire-pour-retrouver-le-sommeil\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.climsom.com\\\/blog\\\/jambes-sans-repos-que-faire-pour-retrouver-le-sommeil\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.climsom.com\\\/blog\\\/jambes-sans-repos-que-faire-pour-retrouver-le-sommeil\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.climsom.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/sommeil_femme_lit.jpg\",\"contentUrl\":\"https:\\\/\\\/www.climsom.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/sommeil_femme_lit.jpg\",\"width\":272,\"height\":200,\"caption\":\"sommeil_femme_lit\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.climsom.com\\\/blog\\\/jambes-sans-repos-que-faire-pour-retrouver-le-sommeil\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.climsom.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jambes sans repos : que faire pour retrouver le sommeil ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.climsom.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.climsom.com\\\/blog\\\/\",\"name\":\"Climsom \u2013 L\u2019innovation bien-\u00eatre\",\"description\":\"Des produits uniques et innovants\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.climsom.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.climsom.com\\\/blog\\\/#\\\/schema\\\/person\\\/ad3a50ac6861affad1c0acafec04bb15\",\"name\":\"climsom\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/62f3ff6adb0a16330bb0476388ef778eb86d72bbb59d42d8466863474896eba8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/62f3ff6adb0a16330bb0476388ef778eb86d72bbb59d42d8466863474896eba8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/62f3ff6adb0a16330bb0476388ef778eb86d72bbb59d42d8466863474896eba8?s=96&d=mm&r=g\",\"caption\":\"climsom\"},\"url\":\"https:\\\/\\\/www.climsom.com\\\/blog\\\/author\\\/climsom\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jambes sans repos : que faire pour retrouver le sommeil ? - Climsom \u2013 L\u2019innovation bien-\u00eatre","description":"Avec le sur-matelas climatis\u00e9 Climsom, r\u00e9duisez les impatiences du syndrome des jambes sans repos pour retrouver un sommeil de qualit\u00e9 !","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.climsom.com\/blog\/jambes-sans-repos-que-faire-pour-retrouver-le-sommeil\/","og_locale":"fr_FR","og_type":"article","og_title":"Jambes sans repos : que faire pour retrouver le sommeil ? - Climsom \u2013 L\u2019innovation bien-\u00eatre","og_description":"Avec le sur-matelas climatis\u00e9 Climsom, r\u00e9duisez les impatiences du syndrome des jambes sans repos pour retrouver un sommeil de qualit\u00e9 !","og_url":"https:\/\/www.climsom.com\/blog\/jambes-sans-repos-que-faire-pour-retrouver-le-sommeil\/","og_site_name":"Climsom \u2013 L\u2019innovation bien-\u00eatre","article_published_time":"2020-01-21T09:06:37+00:00","article_modified_time":"2024-07-30T10:01:28+00:00","og_image":[{"width":272,"height":200,"url":"https:\/\/www.climsom.com\/blog\/wp-content\/uploads\/2020\/01\/sommeil_femme_lit.jpg","type":"image\/jpeg"}],"author":"climsom","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"climsom","Dur\u00e9e de lecture estim\u00e9e":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.climsom.com\/blog\/jambes-sans-repos-que-faire-pour-retrouver-le-sommeil\/#article","isPartOf":{"@id":"https:\/\/www.climsom.com\/blog\/jambes-sans-repos-que-faire-pour-retrouver-le-sommeil\/"},"author":{"name":"climsom","@id":"https:\/\/www.climsom.com\/blog\/#\/schema\/person\/ad3a50ac6861affad1c0acafec04bb15"},"headline":"Jambes sans repos : que faire pour retrouver le sommeil ?","datePublished":"2020-01-21T09:06:37+00:00","dateModified":"2024-07-30T10:01:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.climsom.com\/blog\/jambes-sans-repos-que-faire-pour-retrouver-le-sommeil\/"},"wordCount":1476,"commentCount":0,"image":{"@id":"https:\/\/www.climsom.com\/blog\/jambes-sans-repos-que-faire-pour-retrouver-le-sommeil\/#primaryimage"},"thumbnailUrl":"https:\/\/www.climsom.com\/blog\/wp-content\/uploads\/2020\/01\/sommeil_femme_lit.jpg","keywords":["impatiences","SJSR","trouble du sommeil"],"articleSection":["Sant\u00e9","Sommeil"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.climsom.com\/blog\/jambes-sans-repos-que-faire-pour-retrouver-le-sommeil\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.climsom.com\/blog\/jambes-sans-repos-que-faire-pour-retrouver-le-sommeil\/","url":"https:\/\/www.climsom.com\/blog\/jambes-sans-repos-que-faire-pour-retrouver-le-sommeil\/","name":"Jambes sans repos : que faire pour retrouver le sommeil ? - Climsom \u2013 L\u2019innovation bien-\u00eatre","isPartOf":{"@id":"https:\/\/www.climsom.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.climsom.com\/blog\/jambes-sans-repos-que-faire-pour-retrouver-le-sommeil\/#primaryimage"},"image":{"@id":"https:\/\/www.climsom.com\/blog\/jambes-sans-repos-que-faire-pour-retrouver-le-sommeil\/#primaryimage"},"thumbnailUrl":"https:\/\/www.climsom.com\/blog\/wp-content\/uploads\/2020\/01\/sommeil_femme_lit.jpg","datePublished":"2020-01-21T09:06:37+00:00","dateModified":"2024-07-30T10:01:28+00:00","author":{"@id":"https:\/\/www.climsom.com\/blog\/#\/schema\/person\/ad3a50ac6861affad1c0acafec04bb15"},"description":"Avec le sur-matelas climatis\u00e9 Climsom, r\u00e9duisez les impatiences du syndrome des jambes sans repos pour retrouver un sommeil de qualit\u00e9 !","breadcrumb":{"@id":"https:\/\/www.climsom.com\/blog\/jambes-sans-repos-que-faire-pour-retrouver-le-sommeil\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.climsom.com\/blog\/jambes-sans-repos-que-faire-pour-retrouver-le-sommeil\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.climsom.com\/blog\/jambes-sans-repos-que-faire-pour-retrouver-le-sommeil\/#primaryimage","url":"https:\/\/www.climsom.com\/blog\/wp-content\/uploads\/2020\/01\/sommeil_femme_lit.jpg","contentUrl":"https:\/\/www.climsom.com\/blog\/wp-content\/uploads\/2020\/01\/sommeil_femme_lit.jpg","width":272,"height":200,"caption":"sommeil_femme_lit"},{"@type":"BreadcrumbList","@id":"https:\/\/www.climsom.com\/blog\/jambes-sans-repos-que-faire-pour-retrouver-le-sommeil\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.climsom.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Jambes sans repos : que faire pour retrouver le sommeil ?"}]},{"@type":"WebSite","@id":"https:\/\/www.climsom.com\/blog\/#website","url":"https:\/\/www.climsom.com\/blog\/","name":"Climsom \u2013 L\u2019innovation bien-\u00eatre","description":"Des produits uniques et innovants","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.climsom.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.climsom.com\/blog\/#\/schema\/person\/ad3a50ac6861affad1c0acafec04bb15","name":"climsom","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/62f3ff6adb0a16330bb0476388ef778eb86d72bbb59d42d8466863474896eba8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/62f3ff6adb0a16330bb0476388ef778eb86d72bbb59d42d8466863474896eba8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/62f3ff6adb0a16330bb0476388ef778eb86d72bbb59d42d8466863474896eba8?s=96&d=mm&r=g","caption":"climsom"},"url":"https:\/\/www.climsom.com\/blog\/author\/climsom\/"}]}},"lang":"fr","translations":{"fr":1839},"pll_sync_post":{},"_links":{"self":[{"href":"https:\/\/www.climsom.com\/blog\/wp-json\/wp\/v2\/posts\/1839","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.climsom.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.climsom.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.climsom.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.climsom.com\/blog\/wp-json\/wp\/v2\/comments?post=1839"}],"version-history":[{"count":59,"href":"https:\/\/www.climsom.com\/blog\/wp-json\/wp\/v2\/posts\/1839\/revisions"}],"predecessor-version":[{"id":10679,"href":"https:\/\/www.climsom.com\/blog\/wp-json\/wp\/v2\/posts\/1839\/revisions\/10679"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.climsom.com\/blog\/wp-json\/wp\/v2\/media\/1841"}],"wp:attachment":[{"href":"https:\/\/www.climsom.com\/blog\/wp-json\/wp\/v2\/media?parent=1839"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.climsom.com\/blog\/wp-json\/wp\/v2\/categories?post=1839"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.climsom.com\/blog\/wp-json\/wp\/v2\/tags?post=1839"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}