{"id":6478,"date":"2021-06-22T12:07:07","date_gmt":"2021-06-22T11:07:07","guid":{"rendered":"https:\/\/www.climsom.com\/blog\/?p=6478"},"modified":"2021-06-23T11:42:55","modified_gmt":"2021-06-23T10:42:55","slug":"yeux-secs-solution-efficace-pour-les-soulager","status":"publish","type":"post","link":"https:\/\/www.climsom.com\/blog\/yeux-secs-solution-efficace-pour-les-soulager\/","title":{"rendered":"Yeux secs : une solution simple et efficace pour les soulager !"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Yeux irrit\u00e9s, gonfl\u00e9s, rouges, sensations de picotements&#8230; Nous avons tous d\u00e9j\u00e0 ressenti une g\u00eane au niveau des yeux et eu la sensation d&rsquo;avoir les yeux secs et douloureux, de manquer de larmes.<br>Lorsque cette g\u00eane est ponctuelle et que les raisons semblent claires, une journ\u00e9e \u00e0 la mer ou \u00e0 la piscine par exemple, il y a peu de raisons de s&rsquo;en inqui\u00e9ter.<br><br>En revanche, si vos yeux vous piquent, d\u00e9mangent, ou encore que vous ressentez une grande sensibilit\u00e9 \u00e0 la lumi\u00e8re quotidiennement, vous souffrez alors s\u00fbrement de <strong>s\u00e9cheresse oculaire<\/strong> !<br>Au-del\u00e0 de la g\u00eane et des potentielles douleurs que cela peut vous procurer, il est important de s&rsquo;en pr\u00e9occuper avant que cela n&rsquo;alt\u00e8re votre vue.<br><br>Pas d&rsquo;inqui\u00e9tude, des solutions simples existent !<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Pourquoi avons-nous les yeux secs ?<\/strong><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Des facteurs courants <\/h3>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>L&rsquo;environnement ext\u00e9rieur <\/strong>: vent et pollution peuvent alt\u00e9rer le confort oculaire.<\/li><li><strong>Le chauffage et la climatisation <\/strong>: ils ass\u00e8chent l&rsquo;air et d\u00e9shydratent ainsi plus rapidement la peau et les yeux.<\/li><li><strong>Le port de lentilles de contact <\/strong>: mal adapt\u00e9es \u00e0 la vue ou \u00e0 l&rsquo;\u0153il, les lentilles de contact peuvent \u00eatre \u00e0 l&rsquo;origine d&rsquo;un ass\u00e8chement des yeux.<\/li><li><strong>Le maquillage, et les d\u00e9maquillants<\/strong> : le mascara en particulier peut alt\u00e9rer le r\u00f4le protecteur des cils. Privil\u00e9giez \u00e9galement un d\u00e9maquillant adapt\u00e9 afin d&rsquo;\u00e9viter les yeux secs et irrit\u00e9s.<\/li><li><strong>Infection oculaire :<\/strong> si vous avez l&rsquo;impression de n&rsquo;avoir qu&rsquo;un oeil sec,  il est possible que vous avez un d\u00e9but d&rsquo;infection comme une conjonctivite. Attention alors \u00e0 ne pas vous frotter les yeux, elles sont tr\u00e8s contagieuses !<br><br><\/li><li><strong>LES \u00c9CRANS ! <\/strong><br>Nous sommes de plus en plus nombreux \u00e0 passer de plus en plus de temps devant les \u00e9crans : ordinateurs, t\u00e9l\u00e9vision, t\u00e9l\u00e9phones&#8230; Et ce \u00e9galement de plus en plus t\u00f4t !<br>En effet, l&rsquo;essor des r\u00e9seaux sociaux fait trainer les plus jeunes (mais pas que !) sur leur t\u00e9l\u00e9phone.<br>D\u00e8s les \u00e9tudes sup\u00e9rieures (plus rarement avant), les \u00e9tudiants commencent \u00e0 prendre leurs notes sur ordinateur et passent ainsi d\u00e9j\u00e0 leurs journ\u00e9es devant un ordinateur.<br>Or, plus nous les sollicitons avec les \u00e9crans, plus nous avons les yeux sensibles \u00e0 la lumi\u00e8re&#8230;<br><br>De plus, sans nous en rendre compte, nous clignons moins des yeux lorsque nous sommes concentr\u00e9s devant un \u00e9cran. Lorsqu&rsquo;ils sont \u00e0 la hauteur du regard, les \u00e9crans nous forcent en effet \u00e0 conserver les yeux grands ouverts.<br>Qui n&rsquo;a jamais eu la sensation d&rsquo;avoir les yeux secs et rouges apr\u00e8s une journ\u00e9e compl\u00e8te devant un ordinateur ?<br><br>Les \u00e9crans sont \u00e9galement responsables de <a href=\"https:\/\/www.climsom.com\/blog\/ecrans-confinement-fatigue-oculaire\/\" target=\"_blank\" rel=\"noreferrer noopener\">fatigue oculaire<\/a>.<\/li><\/ul>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.climsom.com\/blog\/wp-content\/uploads\/2021\/06\/yeux-secs-ecrans-300x300.jpg\" alt=\"\" class=\"wp-image-6482\" srcset=\"https:\/\/www.climsom.com\/blog\/wp-content\/uploads\/2021\/06\/yeux-secs-ecrans-300x300.jpg 300w, https:\/\/www.climsom.com\/blog\/wp-content\/uploads\/2021\/06\/yeux-secs-ecrans-150x150.jpg 150w, https:\/\/www.climsom.com\/blog\/wp-content\/uploads\/2021\/06\/yeux-secs-ecrans-768x767.jpg 768w, https:\/\/www.climsom.com\/blog\/wp-content\/uploads\/2021\/06\/yeux-secs-ecrans-75x75.jpg 75w, https:\/\/www.climsom.com\/blog\/wp-content\/uploads\/2021\/06\/yeux-secs-ecrans.jpg 886w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure><\/div>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Le dysfonctionnement des glandes de Meibomius (DGM)<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Les glandes de Meibomius sont les glandes qui produisent le film lipidique (huileux) qui emp\u00eache l&rsquo;\u00e9vaporation des larmes. En pr\u00e9servant une quantit\u00e9 de larmes suffisante, elle \u00e9vite \u00e0 l&rsquo;\u0153il de s&rsquo;ass\u00e9cher.<br>Elles assurent \u00e9galement la lubrification de l&rsquo;\u0153il.<br><br>Lorsque les glandes de Meibomius sont bouch\u00e9es et ne s\u00e9cr\u00e8tent plus assez de liquide huileux, les yeux se retrouvent sans protection et la production lacrymale seule ne suffit pas \u00e0 les hydrater correctement.<br>C&rsquo;est \u00e0 ce moment que nous parlons de s\u00e9cheresse oculaire, ou yeux secs.<br>Le DGM en est ailleurs l&rsquo;une des causes principales, ainsi qu&rsquo;un motif de consultation ophtalmologique tr\u00e8s fr\u00e9quent.<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Comment soulager les yeux secs ?<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Si la g\u00eane n&rsquo;est pas trop intense, vous pouvez commencer par appliquer quelques conseils afin de limiter et soulager la s\u00e9cheresse oculaire :<br><br>&#8211; Porter des lunettes avec un filtre anti-lumi\u00e8re bleue devant les \u00e9crans, m\u00eame si vous n&rsquo;avez pas besoin de correction visuelle. Vous sentirez vos yeux moins fatigu\u00e9s en fin de journ\u00e9e, et \u00e9viterez probablement des maux de t\u00eate.<br>&#8211; Faites des pauses ! Profitez-en pour cligner des yeux ou les fermer quelques instants.<br>&#8211; Humidifier vos yeux \u00e0 l&rsquo;aide de collyres ou gouttes adapt\u00e9es<br>&#8211; Masser d\u00e9licatement vos paupi\u00e8res<br>&#8211; Appliquer des compresses chaudes sur vos yeux, \u00e0 moins qu&rsquo;une autre solution puissent avoir le m\u00eame effet&#8230; <\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Masque chauffant pour les yeux, plus pratique que les compresses chaudes !<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Vous avez d\u00e9j\u00e0 essay\u00e9 les compresses chaudes comme traitement naturel pour les yeux secs ?<br>Pour cela, vous les avez imbiber d&rsquo;eau chaude et les avez appliquer sur vos yeux ?<br>Vous ne saviez pas avec quelle temp\u00e9rature d&rsquo;eau les humidifier ?<br>Les compresses se sont rapidement refroidies ?<br><br>Passez aux <a href=\"https:\/\/www.climsom.com\/fra\/spa-du-regard-dix-masques-autochauffants.php?codeoffer=SpaduRegardPack\" target=\"_blank\" rel=\"noreferrer noopener\">masques auto chauffants pour les yeux SPA du Regard<\/a> et profitez d&rsquo;une <strong>chaleur humide, douce et progressive<\/strong> pendant 30 minutes !<br><br>Beaucoup plus faciles d&rsquo;utilisation, vous n&rsquo;aurez qu&rsquo;\u00e0 les sortir de leur sachet pour qu&rsquo;ils se mettent \u00e0 chauffer progressivement et jusqu&rsquo;\u00e0 41\u00b0C au contact de l&rsquo;air.<br><br>Si vous souffrez du dysfonctionnement des glandes de Meibomius, appliquer r\u00e9guli\u00e8rement de la chaleur sur vos yeux permettra de les d\u00e9boucher progressivement et de liqu\u00e9fier le film lacrymal protecteur.<br>Vous profiterez donc d&rsquo;un soulagement imm\u00e9diat de la g\u00eane, mais \u00e9galement d&rsquo;un <strong>soulagement des yeux secs \u00e0 long terme<\/strong> en aidant vos glandes de Meibomius \u00e0 reprendre leur r\u00f4le !<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><a href=\"https:\/\/www.climsom.com\/fra\/spa-du-regard-dix-masques-autochauffants.php?codeoffer=SpaduRegardPack\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"650\" height=\"280\" src=\"https:\/\/www.climsom.com\/blog\/wp-content\/uploads\/2021\/06\/Spa-du-regard-climsom-homme-boite-650x280.png\" alt=\"Soulager la s\u00e9cheresse oculaire gr\u00e2ce aux masque Spa du Regard\" class=\"wp-image-6499\" srcset=\"https:\/\/www.climsom.com\/blog\/wp-content\/uploads\/2021\/06\/Spa-du-regard-climsom-homme-boite-650x280.png 650w, https:\/\/www.climsom.com\/blog\/wp-content\/uploads\/2021\/06\/Spa-du-regard-climsom-homme-boite-300x129.png 300w, https:\/\/www.climsom.com\/blog\/wp-content\/uploads\/2021\/06\/Spa-du-regard-climsom-homme-boite-768x331.png 768w, https:\/\/www.climsom.com\/blog\/wp-content\/uploads\/2021\/06\/Spa-du-regard-climsom-homme-boite-1140x491.png 1140w, https:\/\/www.climsom.com\/blog\/wp-content\/uploads\/2021\/06\/Spa-du-regard-climsom-homme-boite.png 1371w\" sizes=\"auto, (max-width: 650px) 100vw, 650px\" \/><\/a><figcaption>Boite de 10 masques auto-chauffants pour les yeux \u00e0 usage unique<\/figcaption><\/figure><\/div>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Petite astuce si vous pensez manquer de temps !<\/strong><br>Laissez vos masques pr\u00eats \u00e0 l&#8217;emploi dans votre table de nuit et effectuez votre s\u00e9ance au moment de vous coucher, confortablement dans votre lit !<br>Les masques Spa du Regard \u00e9tant auto-chauffants, vous n&rsquo;aurez m\u00eame pas \u00e0 vous relever pour les mettre au micro-ondes ou les passer sous l&rsquo;eau chaude !<br><br>Vous en profiterez alors pour vous d\u00e9tendre et \u00e9vacuer tout le stress de votre journ\u00e9e.<br>Certains se sont m\u00eame endormis avec le masque sur les yeux&#8230; (on ne d\u00e9noncera personne !)<br><br>De plus, prendre soin de vos yeux le soir pourra \u00e9galement vous \u00e9viter d&rsquo;avoir les yeux secs la nuit, et donc le matin !<br>Avec moins de mouvements oculaires et possiblement des \u00e9crans avant de dormir, il est en effet possible d&rsquo;avoir les yeux secs au r\u00e9veil.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-image is-style-default\"><figure class=\"aligncenter size-large\"><a href=\"https:\/\/www.climsom.com\/fra\/spa-du-regard-dix-masques-autochauffants.php?codeoffer=SpaduRegardPack\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"444\" height=\"300\" src=\"https:\/\/www.climsom.com\/blog\/wp-content\/uploads\/2021\/06\/Spa_du_Regard_couple_lit_01_web_2021-2-444x300.jpg\" alt=\"Masque chauffant pour les yeux Spa du Regard Climsom\" class=\"wp-image-6501\" srcset=\"https:\/\/www.climsom.com\/blog\/wp-content\/uploads\/2021\/06\/Spa_du_Regard_couple_lit_01_web_2021-2-444x300.jpg 444w, https:\/\/www.climsom.com\/blog\/wp-content\/uploads\/2021\/06\/Spa_du_Regard_couple_lit_01_web_2021-2-300x203.jpg 300w, https:\/\/www.climsom.com\/blog\/wp-content\/uploads\/2021\/06\/Spa_du_Regard_couple_lit_01_web_2021-2-768x519.jpg 768w, https:\/\/www.climsom.com\/blog\/wp-content\/uploads\/2021\/06\/Spa_du_Regard_couple_lit_01_web_2021-2-1536x1039.jpg 1536w, https:\/\/www.climsom.com\/blog\/wp-content\/uploads\/2021\/06\/Spa_du_Regard_couple_lit_01_web_2021-2-1140x771.jpg 1140w, https:\/\/www.climsom.com\/blog\/wp-content\/uploads\/2021\/06\/Spa_du_Regard_couple_lit_01_web_2021-2.jpg 1971w\" sizes=\"auto, (max-width: 444px) 100vw, 444px\" \/><\/a><\/figure><\/div>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Vous avez tendance \u00e0 pianoter sur votre t\u00e9l\u00e9phone au lit et dans le noir avant de dormir ?<\/strong><br>Vous l&rsquo;avez s\u00fbrement constat\u00e9, cela peut avoir des cons\u00e9quences n\u00e9fastes sur votre sommeil ainsi que sur vos yeux :<br>&#8211; l&rsquo;\u00e9cran d\u00e9r\u00e8gle votre horloge biologique : il retarde votre endormissement voire vous cr\u00e9e de r\u00e9elles insomnies<br>&#8211; la lumi\u00e8re, et particuli\u00e8rement la lumi\u00e8re bleue, ass\u00e8che vos yeux fatigu\u00e9s<br><br>C&rsquo;est alors un cercle vicieux car la fatigue engendr\u00e9e par le d\u00e9r\u00e8glement de votre sommeil va elle-m\u00eame avoir une incidence sur vos yeux !<br><br>En finissant votre journ\u00e9e au minimum sans \u00e9cran, au mieux avec un masque chauffant pour les yeux, vous reposeriez consid\u00e9rablement vos yeux et retrouverez un meilleur sommeil. Vous retourneriez alors le cercle vicieux en un cercle vertueux. Un rem\u00e8de naturel pour ne plus vous r\u00e9veiller avec les yeux secs le matin !<\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-vivid-cyan-blue-to-vivid-purple-gradient-background has-background\" href=\"https:\/\/www.climsom.com\/fra\/spa-du-regard-dix-masques-autochauffants.php?codeoffer=SpaduRegardPack\" target=\"_blank\" rel=\"noreferrer noopener\">Soulagez mes yeux secs avec les masques chauffants Spa du Regard<\/a><\/div>\n<\/div>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\">CONTACT<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Vous d\u00e9sirez plus d&rsquo;informations ? N&rsquo;h\u00e9sitez pas \u00e0 nous contacter :<br><strong>Par mail :<\/strong> contact@climsom.com<br><strong>Par t\u00e9l\u00e9phone :<\/strong> 02 85 52 44 74<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Yeux rouges, irrit\u00e9s, fatigu\u00e9s&#8230; Les masques chauffants Spa du Regard vous aident \u00e0 les soulager dans l&rsquo;imm\u00e9diat et \u00e0 long terme !<\/p>\n","protected":false},"author":1,"featured_media":6479,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[189,190,74],"class_list":["post-6478","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sante","tag-secheresse-oculaire","tag-spa-du-regard","tag-yeux-secs"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Yeux secs : une solution simple et efficace pour les soulager ! - Climsom \u2013 L\u2019innovation bien-\u00eatre<\/title>\n<meta name=\"description\" content=\"Br\u00fblures, irritations, rougeurs... La chaleur humide vous aide \u00e0 lutter contre la s\u00e9cheresse oculaire et les yeux secs \u00e0 long terme !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.climsom.com\/blog\/yeux-secs-solution-efficace-pour-les-soulager\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Yeux secs : une solution simple et efficace pour les soulager ! - Climsom \u2013 L\u2019innovation bien-\u00eatre\" \/>\n<meta property=\"og:description\" content=\"Br\u00fblures, irritations, rougeurs... La chaleur humide vous aide \u00e0 lutter contre la s\u00e9cheresse oculaire et les yeux secs \u00e0 long terme !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.climsom.com\/blog\/yeux-secs-solution-efficace-pour-les-soulager\/\" \/>\n<meta property=\"og:site_name\" content=\"Climsom \u2013 L\u2019innovation bien-\u00eatre\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-22T11:07:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-23T10:42:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.climsom.com\/blog\/wp-content\/uploads\/2021\/06\/Spa_du_Regard_femme_canape_02_web_2021-e1624352555348.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"280\" \/>\n\t<meta property=\"og:image:height\" content=\"203\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"climsom\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"climsom\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.climsom.com\\\/blog\\\/yeux-secs-solution-efficace-pour-les-soulager\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.climsom.com\\\/blog\\\/yeux-secs-solution-efficace-pour-les-soulager\\\/\"},\"author\":{\"name\":\"climsom\",\"@id\":\"https:\\\/\\\/www.climsom.com\\\/blog\\\/#\\\/schema\\\/person\\\/ad3a50ac6861affad1c0acafec04bb15\"},\"headline\":\"Yeux secs : une solution simple et efficace pour les soulager !\",\"datePublished\":\"2021-06-22T11:07:07+00:00\",\"dateModified\":\"2021-06-23T10:42:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.climsom.com\\\/blog\\\/yeux-secs-solution-efficace-pour-les-soulager\\\/\"},\"wordCount\":1232,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.climsom.com\\\/blog\\\/yeux-secs-solution-efficace-pour-les-soulager\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.climsom.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Spa_du_Regard_femme_canape_02_web_2021-e1624352555348.jpg\",\"keywords\":[\"s\u00e9cheresse oculaire\",\"spa du regard\",\"yeux secs\"],\"articleSection\":[\"Sant\u00e9\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.climsom.com\\\/blog\\\/yeux-secs-solution-efficace-pour-les-soulager\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.climsom.com\\\/blog\\\/yeux-secs-solution-efficace-pour-les-soulager\\\/\",\"url\":\"https:\\\/\\\/www.climsom.com\\\/blog\\\/yeux-secs-solution-efficace-pour-les-soulager\\\/\",\"name\":\"Yeux secs : une solution simple et efficace pour les soulager ! - Climsom \u2013 L\u2019innovation bien-\u00eatre\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.climsom.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.climsom.com\\\/blog\\\/yeux-secs-solution-efficace-pour-les-soulager\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.climsom.com\\\/blog\\\/yeux-secs-solution-efficace-pour-les-soulager\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.climsom.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Spa_du_Regard_femme_canape_02_web_2021-e1624352555348.jpg\",\"datePublished\":\"2021-06-22T11:07:07+00:00\",\"dateModified\":\"2021-06-23T10:42:55+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.climsom.com\\\/blog\\\/#\\\/schema\\\/person\\\/ad3a50ac6861affad1c0acafec04bb15\"},\"description\":\"Br\u00fblures, irritations, rougeurs... La chaleur humide vous aide \u00e0 lutter contre la s\u00e9cheresse oculaire et les yeux secs \u00e0 long terme !\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.climsom.com\\\/blog\\\/yeux-secs-solution-efficace-pour-les-soulager\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.climsom.com\\\/blog\\\/yeux-secs-solution-efficace-pour-les-soulager\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.climsom.com\\\/blog\\\/yeux-secs-solution-efficace-pour-les-soulager\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.climsom.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Spa_du_Regard_femme_canape_02_web_2021-e1624352555348.jpg\",\"contentUrl\":\"https:\\\/\\\/www.climsom.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Spa_du_Regard_femme_canape_02_web_2021-e1624352555348.jpg\",\"width\":280,\"height\":203,\"caption\":\"masque yeux chauffant Spa du Regard\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.climsom.com\\\/blog\\\/yeux-secs-solution-efficace-pour-les-soulager\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.climsom.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Yeux secs : une solution simple et efficace pour les soulager !\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.climsom.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.climsom.com\\\/blog\\\/\",\"name\":\"Climsom \u2013 L\u2019innovation bien-\u00eatre\",\"description\":\"Des produits uniques et innovants\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.climsom.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.climsom.com\\\/blog\\\/#\\\/schema\\\/person\\\/ad3a50ac6861affad1c0acafec04bb15\",\"name\":\"climsom\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/62f3ff6adb0a16330bb0476388ef778eb86d72bbb59d42d8466863474896eba8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/62f3ff6adb0a16330bb0476388ef778eb86d72bbb59d42d8466863474896eba8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/62f3ff6adb0a16330bb0476388ef778eb86d72bbb59d42d8466863474896eba8?s=96&d=mm&r=g\",\"caption\":\"climsom\"},\"url\":\"https:\\\/\\\/www.climsom.com\\\/blog\\\/author\\\/climsom\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Yeux secs : une solution simple et efficace pour les soulager ! - Climsom \u2013 L\u2019innovation bien-\u00eatre","description":"Br\u00fblures, irritations, rougeurs... La chaleur humide vous aide \u00e0 lutter contre la s\u00e9cheresse oculaire et les yeux secs \u00e0 long terme !","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.climsom.com\/blog\/yeux-secs-solution-efficace-pour-les-soulager\/","og_locale":"fr_FR","og_type":"article","og_title":"Yeux secs : une solution simple et efficace pour les soulager ! - Climsom \u2013 L\u2019innovation bien-\u00eatre","og_description":"Br\u00fblures, irritations, rougeurs... La chaleur humide vous aide \u00e0 lutter contre la s\u00e9cheresse oculaire et les yeux secs \u00e0 long terme !","og_url":"https:\/\/www.climsom.com\/blog\/yeux-secs-solution-efficace-pour-les-soulager\/","og_site_name":"Climsom \u2013 L\u2019innovation bien-\u00eatre","article_published_time":"2021-06-22T11:07:07+00:00","article_modified_time":"2021-06-23T10:42:55+00:00","og_image":[{"width":280,"height":203,"url":"https:\/\/www.climsom.com\/blog\/wp-content\/uploads\/2021\/06\/Spa_du_Regard_femme_canape_02_web_2021-e1624352555348.jpg","type":"image\/jpeg"}],"author":"climsom","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"climsom","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.climsom.com\/blog\/yeux-secs-solution-efficace-pour-les-soulager\/#article","isPartOf":{"@id":"https:\/\/www.climsom.com\/blog\/yeux-secs-solution-efficace-pour-les-soulager\/"},"author":{"name":"climsom","@id":"https:\/\/www.climsom.com\/blog\/#\/schema\/person\/ad3a50ac6861affad1c0acafec04bb15"},"headline":"Yeux secs : une solution simple et efficace pour les soulager !","datePublished":"2021-06-22T11:07:07+00:00","dateModified":"2021-06-23T10:42:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.climsom.com\/blog\/yeux-secs-solution-efficace-pour-les-soulager\/"},"wordCount":1232,"commentCount":0,"image":{"@id":"https:\/\/www.climsom.com\/blog\/yeux-secs-solution-efficace-pour-les-soulager\/#primaryimage"},"thumbnailUrl":"https:\/\/www.climsom.com\/blog\/wp-content\/uploads\/2021\/06\/Spa_du_Regard_femme_canape_02_web_2021-e1624352555348.jpg","keywords":["s\u00e9cheresse oculaire","spa du regard","yeux secs"],"articleSection":["Sant\u00e9"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.climsom.com\/blog\/yeux-secs-solution-efficace-pour-les-soulager\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.climsom.com\/blog\/yeux-secs-solution-efficace-pour-les-soulager\/","url":"https:\/\/www.climsom.com\/blog\/yeux-secs-solution-efficace-pour-les-soulager\/","name":"Yeux secs : une solution simple et efficace pour les soulager ! - Climsom \u2013 L\u2019innovation bien-\u00eatre","isPartOf":{"@id":"https:\/\/www.climsom.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.climsom.com\/blog\/yeux-secs-solution-efficace-pour-les-soulager\/#primaryimage"},"image":{"@id":"https:\/\/www.climsom.com\/blog\/yeux-secs-solution-efficace-pour-les-soulager\/#primaryimage"},"thumbnailUrl":"https:\/\/www.climsom.com\/blog\/wp-content\/uploads\/2021\/06\/Spa_du_Regard_femme_canape_02_web_2021-e1624352555348.jpg","datePublished":"2021-06-22T11:07:07+00:00","dateModified":"2021-06-23T10:42:55+00:00","author":{"@id":"https:\/\/www.climsom.com\/blog\/#\/schema\/person\/ad3a50ac6861affad1c0acafec04bb15"},"description":"Br\u00fblures, irritations, rougeurs... La chaleur humide vous aide \u00e0 lutter contre la s\u00e9cheresse oculaire et les yeux secs \u00e0 long terme !","breadcrumb":{"@id":"https:\/\/www.climsom.com\/blog\/yeux-secs-solution-efficace-pour-les-soulager\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.climsom.com\/blog\/yeux-secs-solution-efficace-pour-les-soulager\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.climsom.com\/blog\/yeux-secs-solution-efficace-pour-les-soulager\/#primaryimage","url":"https:\/\/www.climsom.com\/blog\/wp-content\/uploads\/2021\/06\/Spa_du_Regard_femme_canape_02_web_2021-e1624352555348.jpg","contentUrl":"https:\/\/www.climsom.com\/blog\/wp-content\/uploads\/2021\/06\/Spa_du_Regard_femme_canape_02_web_2021-e1624352555348.jpg","width":280,"height":203,"caption":"masque yeux chauffant Spa du Regard"},{"@type":"BreadcrumbList","@id":"https:\/\/www.climsom.com\/blog\/yeux-secs-solution-efficace-pour-les-soulager\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.climsom.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Yeux secs : une solution simple et efficace pour les soulager !"}]},{"@type":"WebSite","@id":"https:\/\/www.climsom.com\/blog\/#website","url":"https:\/\/www.climsom.com\/blog\/","name":"Climsom \u2013 L\u2019innovation bien-\u00eatre","description":"Des produits uniques et innovants","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.climsom.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.climsom.com\/blog\/#\/schema\/person\/ad3a50ac6861affad1c0acafec04bb15","name":"climsom","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/62f3ff6adb0a16330bb0476388ef778eb86d72bbb59d42d8466863474896eba8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/62f3ff6adb0a16330bb0476388ef778eb86d72bbb59d42d8466863474896eba8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/62f3ff6adb0a16330bb0476388ef778eb86d72bbb59d42d8466863474896eba8?s=96&d=mm&r=g","caption":"climsom"},"url":"https:\/\/www.climsom.com\/blog\/author\/climsom\/"}]}},"lang":"fr","translations":{"fr":6478},"pll_sync_post":{},"_links":{"self":[{"href":"https:\/\/www.climsom.com\/blog\/wp-json\/wp\/v2\/posts\/6478","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.climsom.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.climsom.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.climsom.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.climsom.com\/blog\/wp-json\/wp\/v2\/comments?post=6478"}],"version-history":[{"count":25,"href":"https:\/\/www.climsom.com\/blog\/wp-json\/wp\/v2\/posts\/6478\/revisions"}],"predecessor-version":[{"id":6515,"href":"https:\/\/www.climsom.com\/blog\/wp-json\/wp\/v2\/posts\/6478\/revisions\/6515"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.climsom.com\/blog\/wp-json\/wp\/v2\/media\/6479"}],"wp:attachment":[{"href":"https:\/\/www.climsom.com\/blog\/wp-json\/wp\/v2\/media?parent=6478"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.climsom.com\/blog\/wp-json\/wp\/v2\/categories?post=6478"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.climsom.com\/blog\/wp-json\/wp\/v2\/tags?post=6478"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}