{"id":7906,"date":"2023-02-06T10:57:54","date_gmt":"2023-02-06T09:57:54","guid":{"rendered":"https:\/\/www.climsom.com\/blog\/?p=7906"},"modified":"2023-10-30T15:42:41","modified_gmt":"2023-10-30T14:42:41","slug":"migraine-enceinte-comment-gerer-les-crises","status":"publish","type":"post","link":"https:\/\/www.climsom.com\/blog\/migraine-enceinte-comment-gerer-les-crises\/","title":{"rendered":"Migraine enceinte : comment g\u00e9rer les crises ?"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Comment calmer une migraine enceinte&nbsp;? Une question que se posent beaucoup de futures mamans pendant leur grossesse. Que la migraine s\u2019invite d\u00e8s le premier trimestre, \u00e0 4 mois ou au cours du 3<sup>\u00e8me<\/sup> trimestre, qu\u2019il s\u2019agisse d\u2019une migraine ophtalmique ou d\u2019une migraine sans aura, ces c\u00e9phal\u00e9es lancinantes ne sont pas les bienvenues. Alors comment s\u2019en d\u00e9barrasser le plus rapidement possible&nbsp;? Plut\u00f4t que de prendre votre mal (de t\u00eate) en patience, voici comment faire passer une migraine pendant la grossesse.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Migraine et grossesse&nbsp;: quel traitement naturel&nbsp;?<\/strong><\/h2>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">D\u00e8s les premiers sympt\u00f4mes de la migraine (douleurs pulsatiles dans le cr\u00e2ne, hypersensibilit\u00e9 \u00e0 la lumi\u00e8re et au son, naus\u00e9es, vomissements ou troubles visuels pour les cas de migraines ophtalmiques\u2026), essayez de vous isoler le plus rapidement possible <strong>dans le noir, au calme et au frais<\/strong>. La lumi\u00e8re, le bruit et la chaleur peuvent en effet exacerber la crise migraineuse amplifiant les maux de t\u00eate.<\/p>\n\n\n\n<p class=\"has-luminous-vivid-amber-background-color has-background wp-block-paragraph\">On conseille souvent de prendre du caf\u00e9 pour son effet vasoconstricteur mais enceinte, il vaut mieux limiter la consommation de caf\u00e9ine.<br><br>Bonne nouvelle : cet effet vasoconstricteur peut \u00eatre obtenu autrement. Par une solution \u00e0 la fois <strong>naturelle et puissante<\/strong> pour soulager migraines, maux de t\u00eate et c\u00e9phal\u00e9es de tension : le <strong>froid<\/strong>.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-align-left has-background wp-block-paragraph\" style=\"background-color:#dceef9\"><strong>4 bonnes raisons d\u2019appliquer du froid pour faire passer une migraine enceinte<\/strong><br><br>&gt; le froid est <strong>antalgique<\/strong>&nbsp;: il calme imm\u00e9diatement les nerfs, le froid est un anti-douleur naturel.<br>&gt; le froid est <strong>anti-inflammatoire<\/strong>&nbsp;: il calme les inflammations responsables de vos migraines.<br>&gt; le froid est <strong>vasoconstricteur<\/strong>&nbsp;: il dynamise la circulation sanguine.<br>&gt; le froid <strong>facilite l\u2019endormissement<\/strong>&nbsp;: il envoie au cerveau le signal du sommeil pour que vous puissiez rapidement vous endormir, le sommeil \u00e9tant un alli\u00e9 pour faire passer naturellement la migraine. En effet, pour s\u2019endormir la temp\u00e9rature du cerveau doit diminuer d\u20191\u00b0C. En appliquant de la fraicheur au niveau de la t\u00eate, non seulement on soulage les douleurs mais on favorise \u00e9galement l\u2019endormissement et le sommeil.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Voil\u00e0 pourquoi on recommande d\u2019appliquer un linge humide ou une poche de glace sur le front.<br>Sauf que, on ne va pas vous mentir, il y a un vrai probl\u00e8me avec ces solutions.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La migraine est bien plus qu\u2019un gros mal de t\u00eate<\/strong>&nbsp;: il faut donc un rafraichissement en cons\u00e9quence.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tr\u00e8s rapidement, votre chaleur corporelle va r\u00e9chauffer le linge ou la poche de glace. Le r\u00e9pit sera donc de (trop) courte dur\u00e9e. <br>Par ailleurs la poche de glace ne ciblera qu\u2019une zone partielle de votre cr\u00e2ne. <br>Et puis maintenir une poche de glace est assez p\u00e9nible&nbsp;!<br>Enfin, vous serez mouill\u00e9e&nbsp;et vous devrez vous relever pour vous \u00e9ponger. <br>Qui a envie de \u00e7a en pleine crise de migraine&nbsp;?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les migraines sont vraiment insupportables et donnent envie de se cogner la t\u00eate contre les murs. Douleurs pulsatiles, coups de marteau, envie de hurler\u2026 et pas moyen de prendre des m\u00e9dicaments pour soulager une migraine enceinte&nbsp;! <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Heureusement, il existe une solution bien plus pratique pour ne plus souffrir le martyre.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><a href=\"https:\/\/www.climsom.com\/fra\/bonnet-anti-migraine-poche-gel-froid.php?codeoffer=BonnetMigraineN\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/www.climsom.com\/blog\/wp-content\/uploads\/2023\/02\/Femme-lit-bonnet-450x300.jpg\" alt=\"Femme-enceinte-lit-bonnet-anti-migraine\" class=\"wp-image-8207\"\/><\/a><\/figure>\n<\/div>\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Le bonnet rafraichissant est une <strong>alternative&nbsp;efficace pour rendre supportable la douleur<\/strong> le temps que la crise passe. Gr\u00e2ce au froid mais pas seulement.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-background wp-block-paragraph\" style=\"background-color:#dceef9\">Les 4 points forts d&rsquo;un <strong>bon<\/strong> bonnet rafraichissant contre la migraine :<br><br>1. <strong>Sa fra\u00eecheur longue dur\u00e9e<\/strong> <strong>: <\/strong>regardez bien la contenance en gel rafraichissant !<br><br>2. <strong>Sa mati\u00e8re : <\/strong>elle doit absolument \u00eatre sans odeur pour ne pas raviver la crise. Et assurez-vous que son toucher soit soyeux pour un plaisir tactile qui participe au r\u00e9confort.<br><br>3. <strong>Son \u00e9paisseur, sa couleur et sa hauteur\u00a0: <\/strong>les 3 indispensables pour bloquer toute source lumineuse<br><br>4. <strong>Son confort et sa qualit\u00e9 de fabrication<\/strong> : vous n&rsquo;avez pas envie de jeter votre masque migraine froid apr\u00e8s 2 utilisations !<br><\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button aligncenter is-style-outline is-style-outline--1\"><a class=\"wp-block-button__link has-black-color has-text-color has-background wp-element-button\" href=\"https:\/\/www.climsom.com\/blog\/comment-bien-choisir-son-bonnet-anti-migraine\" style=\"background-color:#dceef9\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Bien choisir son bonnet froid pour lutter contre la migraine pendant votre grossesse<\/strong><\/a><\/div>\n<\/div>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Migraine enceinte : rep\u00e9rez les facteurs d\u00e9clencheurs<\/h2>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00eame si vous n\u2019avez jamais eu de migraines jusqu\u2019\u00e0 pr\u00e9sent, vous pouvez \u00eatre concern\u00e9e pendant votre grossesse par de fortes c\u00e9phal\u00e9es et plus particuli\u00e8rement lors des 3 premiers mois de grossesse. Les chamboulements du premier trimestre de grossesse&nbsp;peuvent \u00eatre responsables et notamment&nbsp;:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; les changements hormonaux<br>&#8211; le stress et la fatigue <br>&#8211; la d\u00e9shydratation possible \u00e0 cause des naus\u00e9es et vomissements.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">N&rsquo;h\u00e9sitez pas \u00e0 consulter votre m\u00e9decin traitant pour s\u2019assurer que ces maux de t\u00eate n\u2019ont pas une autre cause.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Voici aussi quelques questions \u00e0 vous poser pour mieux cerner les d\u00e9clencheurs de ces migraines&nbsp;:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Vous hydratez-vous r\u00e9guli\u00e8rement&nbsp;?<\/li>\n\n\n\n<li>Dormez-vous suffisamment&nbsp;?<\/li>\n\n\n\n<li>Avez-vous la possibilit\u00e9 de vous accorder des p\u00e9riodes de repos en journ\u00e9e&nbsp;?<\/li>\n\n\n\n<li>Sentez-vous que vous \u00eates stress\u00e9e&nbsp;?<\/li>\n\n\n\n<li>Faites-vous des exercices de relaxation (yoga pr\u00e9natal ou gymnastique douce)&nbsp;ou de respiration (<a href=\"https:\/\/www.climsom.com\/blog\/stress-et-anxiete-bienfaits-coherence-cardiaque\/\" target=\"_blank\" rel=\"noreferrer noopener\">coh\u00e9rence cardiaque<\/a>)&nbsp;?<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous avez r\u00e9pondu oui \u00e0 toutes ces questions, vous faites d\u00e9j\u00e0 beaucoup pour r\u00e9duire les c\u00e9phal\u00e9es. Mais cela peut ne pas suffire. Il existe de nombreux d\u00e9clencheurs de migraines, certains aliments par exemple, l\u2019environnement peut aussi jouer (lumi\u00e8res vives, bruits forts, chaleur\u2026). Il peut \u00eatre int\u00e9ressant de tenir un journal des crises migraineuses pour identifier les facteurs d\u00e9clencheurs communs et mieux les \u00e9viter.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Afin de vivre votre grossesse le plus sereinement possible, n\u2019h\u00e9sitez pas \u00e0 consulter les articles ci-dessous&nbsp;:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.climsom.com\/blog\/grossesse-et-jambes-lourdes-quelle-solution-la-nuit\/\" target=\"_blank\" rel=\"noreferrer noopener\">Grossesse et jambes lourdes : quelle solution la nuit ?<\/a><br><a href=\"https:\/\/www.climsom.com\/blog\/douleurs-ligamentaires-et-syndrome-de-lacomme-grossesse-oreiller-rafraichissant\/\" target=\"_blank\" rel=\"noreferrer noopener\">Douleurs ligamentaires et syndrome de Lacomme pendant la grossesse<\/a><br><a href=\"https:\/\/www.climsom.com\/fra\/grossesse-enceinte-chaleur-Climsom.php\" target=\"_blank\" rel=\"noreferrer noopener\">U<\/a><a href=\"https:\/\/www.climsom.com\/fra\/grossesse-enceinte-chaleur-Climsom.php\">ne grossesse en pleine forme avec Climsom !<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ne souffrez plus le martyre, il existe une solution. Voici comment faire passer une migraine pendant la grossesse sans m\u00e9dicament.<\/p>\n","protected":false},"author":1,"featured_media":7958,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,8],"tags":[236,231,235,234,46],"class_list":["post-7906","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sante","category-sommeil","tag-cephalee","tag-douleur","tag-enceinte","tag-grossesse","tag-migraine"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Migraine enceinte : comment g\u00e9rer les crises ?<\/title>\n<meta name=\"description\" content=\"Ne souffrez plus le martyre, il existe une solution contre la migraine enceinte. Voici comment faire passer une migraine pendant la grossesse.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.climsom.com\/blog\/migraine-enceinte-comment-gerer-les-crises\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Migraine enceinte : comment g\u00e9rer les crises ?\" \/>\n<meta property=\"og:description\" content=\"Ne souffrez plus le martyre, il existe une solution contre la migraine enceinte. Voici comment faire passer une migraine pendant la grossesse.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.climsom.com\/blog\/migraine-enceinte-comment-gerer-les-crises\/\" \/>\n<meta property=\"og:site_name\" content=\"Climsom \u2013 L\u2019innovation bien-\u00eatre\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-06T09:57:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-30T14:42:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.climsom.com\/blog\/wp-content\/uploads\/2023\/02\/femme-enceinte-avec-migraine-e1675863768516.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"climsom\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"climsom\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.climsom.com\\\/blog\\\/migraine-enceinte-comment-gerer-les-crises\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.climsom.com\\\/blog\\\/migraine-enceinte-comment-gerer-les-crises\\\/\"},\"author\":{\"name\":\"climsom\",\"@id\":\"https:\\\/\\\/www.climsom.com\\\/blog\\\/#\\\/schema\\\/person\\\/ad3a50ac6861affad1c0acafec04bb15\"},\"headline\":\"Migraine enceinte : comment g\u00e9rer les crises ?\",\"datePublished\":\"2023-02-06T09:57:54+00:00\",\"dateModified\":\"2023-10-30T14:42:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.climsom.com\\\/blog\\\/migraine-enceinte-comment-gerer-les-crises\\\/\"},\"wordCount\":961,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.climsom.com\\\/blog\\\/migraine-enceinte-comment-gerer-les-crises\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.climsom.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/femme-enceinte-avec-migraine-e1675863768516.jpg\",\"keywords\":[\"c\u00e9phal\u00e9e\",\"douleur\",\"enceinte\",\"grossesse\",\"migraine\"],\"articleSection\":[\"Sant\u00e9\",\"Sommeil\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.climsom.com\\\/blog\\\/migraine-enceinte-comment-gerer-les-crises\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.climsom.com\\\/blog\\\/migraine-enceinte-comment-gerer-les-crises\\\/\",\"url\":\"https:\\\/\\\/www.climsom.com\\\/blog\\\/migraine-enceinte-comment-gerer-les-crises\\\/\",\"name\":\"Migraine enceinte : comment g\u00e9rer les crises ?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.climsom.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.climsom.com\\\/blog\\\/migraine-enceinte-comment-gerer-les-crises\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.climsom.com\\\/blog\\\/migraine-enceinte-comment-gerer-les-crises\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.climsom.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/femme-enceinte-avec-migraine-e1675863768516.jpg\",\"datePublished\":\"2023-02-06T09:57:54+00:00\",\"dateModified\":\"2023-10-30T14:42:41+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.climsom.com\\\/blog\\\/#\\\/schema\\\/person\\\/ad3a50ac6861affad1c0acafec04bb15\"},\"description\":\"Ne souffrez plus le martyre, il existe une solution contre la migraine enceinte. Voici comment faire passer une migraine pendant la grossesse.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.climsom.com\\\/blog\\\/migraine-enceinte-comment-gerer-les-crises\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.climsom.com\\\/blog\\\/migraine-enceinte-comment-gerer-les-crises\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.climsom.com\\\/blog\\\/migraine-enceinte-comment-gerer-les-crises\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.climsom.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/femme-enceinte-avec-migraine-e1675863768516.jpg\",\"contentUrl\":\"https:\\\/\\\/www.climsom.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/femme-enceinte-avec-migraine-e1675863768516.jpg\",\"width\":300,\"height\":200,\"caption\":\"femme-enceinte-avec-migraine\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.climsom.com\\\/blog\\\/migraine-enceinte-comment-gerer-les-crises\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.climsom.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Migraine enceinte : comment g\u00e9rer les crises ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.climsom.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.climsom.com\\\/blog\\\/\",\"name\":\"Climsom \u2013 L\u2019innovation bien-\u00eatre\",\"description\":\"Des produits uniques et innovants\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.climsom.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.climsom.com\\\/blog\\\/#\\\/schema\\\/person\\\/ad3a50ac6861affad1c0acafec04bb15\",\"name\":\"climsom\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/62f3ff6adb0a16330bb0476388ef778eb86d72bbb59d42d8466863474896eba8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/62f3ff6adb0a16330bb0476388ef778eb86d72bbb59d42d8466863474896eba8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/62f3ff6adb0a16330bb0476388ef778eb86d72bbb59d42d8466863474896eba8?s=96&d=mm&r=g\",\"caption\":\"climsom\"},\"url\":\"https:\\\/\\\/www.climsom.com\\\/blog\\\/author\\\/climsom\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Migraine enceinte : comment g\u00e9rer les crises ?","description":"Ne souffrez plus le martyre, il existe une solution contre la migraine enceinte. Voici comment faire passer une migraine pendant la grossesse.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.climsom.com\/blog\/migraine-enceinte-comment-gerer-les-crises\/","og_locale":"fr_FR","og_type":"article","og_title":"Migraine enceinte : comment g\u00e9rer les crises ?","og_description":"Ne souffrez plus le martyre, il existe une solution contre la migraine enceinte. Voici comment faire passer une migraine pendant la grossesse.","og_url":"https:\/\/www.climsom.com\/blog\/migraine-enceinte-comment-gerer-les-crises\/","og_site_name":"Climsom \u2013 L\u2019innovation bien-\u00eatre","article_published_time":"2023-02-06T09:57:54+00:00","article_modified_time":"2023-10-30T14:42:41+00:00","og_image":[{"width":300,"height":200,"url":"https:\/\/www.climsom.com\/blog\/wp-content\/uploads\/2023\/02\/femme-enceinte-avec-migraine-e1675863768516.jpg","type":"image\/jpeg"}],"author":"climsom","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"climsom","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.climsom.com\/blog\/migraine-enceinte-comment-gerer-les-crises\/#article","isPartOf":{"@id":"https:\/\/www.climsom.com\/blog\/migraine-enceinte-comment-gerer-les-crises\/"},"author":{"name":"climsom","@id":"https:\/\/www.climsom.com\/blog\/#\/schema\/person\/ad3a50ac6861affad1c0acafec04bb15"},"headline":"Migraine enceinte : comment g\u00e9rer les crises ?","datePublished":"2023-02-06T09:57:54+00:00","dateModified":"2023-10-30T14:42:41+00:00","mainEntityOfPage":{"@id":"https:\/\/www.climsom.com\/blog\/migraine-enceinte-comment-gerer-les-crises\/"},"wordCount":961,"commentCount":0,"image":{"@id":"https:\/\/www.climsom.com\/blog\/migraine-enceinte-comment-gerer-les-crises\/#primaryimage"},"thumbnailUrl":"https:\/\/www.climsom.com\/blog\/wp-content\/uploads\/2023\/02\/femme-enceinte-avec-migraine-e1675863768516.jpg","keywords":["c\u00e9phal\u00e9e","douleur","enceinte","grossesse","migraine"],"articleSection":["Sant\u00e9","Sommeil"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.climsom.com\/blog\/migraine-enceinte-comment-gerer-les-crises\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.climsom.com\/blog\/migraine-enceinte-comment-gerer-les-crises\/","url":"https:\/\/www.climsom.com\/blog\/migraine-enceinte-comment-gerer-les-crises\/","name":"Migraine enceinte : comment g\u00e9rer les crises ?","isPartOf":{"@id":"https:\/\/www.climsom.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.climsom.com\/blog\/migraine-enceinte-comment-gerer-les-crises\/#primaryimage"},"image":{"@id":"https:\/\/www.climsom.com\/blog\/migraine-enceinte-comment-gerer-les-crises\/#primaryimage"},"thumbnailUrl":"https:\/\/www.climsom.com\/blog\/wp-content\/uploads\/2023\/02\/femme-enceinte-avec-migraine-e1675863768516.jpg","datePublished":"2023-02-06T09:57:54+00:00","dateModified":"2023-10-30T14:42:41+00:00","author":{"@id":"https:\/\/www.climsom.com\/blog\/#\/schema\/person\/ad3a50ac6861affad1c0acafec04bb15"},"description":"Ne souffrez plus le martyre, il existe une solution contre la migraine enceinte. Voici comment faire passer une migraine pendant la grossesse.","breadcrumb":{"@id":"https:\/\/www.climsom.com\/blog\/migraine-enceinte-comment-gerer-les-crises\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.climsom.com\/blog\/migraine-enceinte-comment-gerer-les-crises\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.climsom.com\/blog\/migraine-enceinte-comment-gerer-les-crises\/#primaryimage","url":"https:\/\/www.climsom.com\/blog\/wp-content\/uploads\/2023\/02\/femme-enceinte-avec-migraine-e1675863768516.jpg","contentUrl":"https:\/\/www.climsom.com\/blog\/wp-content\/uploads\/2023\/02\/femme-enceinte-avec-migraine-e1675863768516.jpg","width":300,"height":200,"caption":"femme-enceinte-avec-migraine"},{"@type":"BreadcrumbList","@id":"https:\/\/www.climsom.com\/blog\/migraine-enceinte-comment-gerer-les-crises\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.climsom.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Migraine enceinte : comment g\u00e9rer les crises ?"}]},{"@type":"WebSite","@id":"https:\/\/www.climsom.com\/blog\/#website","url":"https:\/\/www.climsom.com\/blog\/","name":"Climsom \u2013 L\u2019innovation bien-\u00eatre","description":"Des produits uniques et innovants","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.climsom.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.climsom.com\/blog\/#\/schema\/person\/ad3a50ac6861affad1c0acafec04bb15","name":"climsom","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/62f3ff6adb0a16330bb0476388ef778eb86d72bbb59d42d8466863474896eba8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/62f3ff6adb0a16330bb0476388ef778eb86d72bbb59d42d8466863474896eba8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/62f3ff6adb0a16330bb0476388ef778eb86d72bbb59d42d8466863474896eba8?s=96&d=mm&r=g","caption":"climsom"},"url":"https:\/\/www.climsom.com\/blog\/author\/climsom\/"}]}},"lang":"fr","translations":{"fr":7906},"pll_sync_post":{},"_links":{"self":[{"href":"https:\/\/www.climsom.com\/blog\/wp-json\/wp\/v2\/posts\/7906","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.climsom.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.climsom.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.climsom.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.climsom.com\/blog\/wp-json\/wp\/v2\/comments?post=7906"}],"version-history":[{"count":62,"href":"https:\/\/www.climsom.com\/blog\/wp-json\/wp\/v2\/posts\/7906\/revisions"}],"predecessor-version":[{"id":9207,"href":"https:\/\/www.climsom.com\/blog\/wp-json\/wp\/v2\/posts\/7906\/revisions\/9207"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.climsom.com\/blog\/wp-json\/wp\/v2\/media\/7958"}],"wp:attachment":[{"href":"https:\/\/www.climsom.com\/blog\/wp-json\/wp\/v2\/media?parent=7906"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.climsom.com\/blog\/wp-json\/wp\/v2\/categories?post=7906"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.climsom.com\/blog\/wp-json\/wp\/v2\/tags?post=7906"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}